{"id":13345,"date":"2019-06-17T02:02:16","date_gmt":"2019-06-16T18:02:16","guid":{"rendered":"https:\/\/wiweka.com\/cara-menghipnotis-orang-lain-secara-instan\/"},"modified":"2024-03-01T11:48:37","modified_gmt":"2024-03-01T03:48:37","slug":"cara-menghipnotis-orang-lain-secara-instan","status":"publish","type":"post","link":"https:\/\/wiweka.com\/id\/cara-menghipnotis-orang-lain-secara-instan\/","title":{"rendered":"Cara Menghipnotis Orang Lain Secara Instan"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/wiweka.com\/wp-content\/uploads\/2019\/06\/How-t&#x43E;-Hypnotize-S&#x43E;m&#x435;&#x43E;n&#x435;-Instantly.jpg\" alt=\"\" class=\"wp-image-1616\" title=\"\"><\/figure><\/div>\n\n<p class=\"wp-block-paragraph\">Akan ada banyak orang yang menganggap konsep hipnotis sangat menarik. Banyak yang mengasosiasikan hipnotis dengan semacam sihir, tapi biar saya beritahu, ini lebih seperti permainan pikiran. Jika Anda tahu cara menghipnotis secara instan, Anda dapat menggunakan perintah untuk masuk jauh ke dalam jiwa individu tersebut.<\/p>\n\n<!--more-->\n\n<p class=\"wp-block-paragraph\">Beberapa kesalahpahaman yang ada tentang hipnosis harus dihilangkan. Selama sesi, subjek tidak berada di bawah kendali penghipnotis. Subjek tidak mengungkapkan apa pun yang tidak ingin dia ungkapkan. Anda tidak boleh menganggap hipnosis sebagai cara untuk menyelesaikan sesuatu dengan sendirinya. Ketika Anda menghipnotis seseorang dengan izinnya, metode ini disebut hipnoterapi. Metode ini telah digunakan untuk menyembuhkan trauma emosional dan beberapa kondisi medis seperti insomnia, gangguan obsesif kompulsif, gagap, dan rasa malu. Teknik hipnosis diri juga dapat digunakan untuk berhenti merokok. Jika Anda kelebihan berat badan, Anda bisa mendapatkan manfaat dari hipnosis penurunan berat badan. Kini, hipnosis telah muncul sebagai alat untuk menyembuhkan orang.<\/p>\n\n<p class=\"wp-block-paragraph\">Banyak psikolog menggunakan hipnotis sebagai alat untuk memahami kondisi emosional pasien mereka. Ketika beberapa ahli hipnotis melakukan pertunjukan panggung, mereka juga menggunakan metode lain. Banyak orang yang menggunakan teknik hipnotis untuk menghipnotis orang lain tanpa mereka sadari. Ini disebut hipnosis terselubung. Karena subjek tidak menyadari fakta bahwa ia sedang dihipnotis, maka perlawanannya akan berkurang dan subjek dapat dengan mudah menuruti perintah hipnotis kita. Teknik ini harus diserahkan kepada psikolog. Jika Anda memiliki ketertarikan pada hipnotis, akan lebih baik untuk menghipnotis orang dengan terlebih dahulu meminta izin dari mereka.<\/p>\n\n<h4 class=\"wp-block-heading\">Hipnotis Terselubung<\/h4>\n\n<p class=\"wp-block-paragraph\">  Mempelajari teknik hipnosis membutuhkan banyak latihan, kesabaran, dan kepercayaan diri. Sangatlah penting bahwa orang yang ingin Anda hipnotis merasa aman bersama Anda. Hipnotis adalah kondisi pikiran yang alami, seperti hanyut dalam proses berpikir. Jika orang yang ingin Anda hipnotis ketakutan saat memikirkan dihipnotis, sesi ini tidak akan berhasil. Libatkan subjek dalam percakapan dan buat dia merasa rileks. Banyak ahli hipnotis menggunakan metode yang disebut hipnotis percakapan. Proses ini melibatkan komunikasi dengan pikiran bawah sadar orang lain tanpa sepengetahuannya. Hal ini dilakukan dengan memasukkan sugesti hipnotis secara halus ke dalam percakapan kita dengan subjek dan memperkuatnya melalui pengulangan. Ini tidak mudah. Anda akan membutuhkan pelatihan hipnoterapi dan banyak latihan.<\/p>\n\n<h4 class=\"wp-block-heading\"><strong>Hipnoterapi<\/strong><\/h4>\n\n<p class=\"wp-block-paragraph\">  Jika Anda ingin mencoba hipnoterapi, Anda dapat mengikuti petunjuk berikut ini. Anda harus mulai dengan membuat orang tersebut merasa rileks. Setelah orang tersebut merasa rileks, Anda dapat mulai berbicara dengan suara yang menenangkan. Modulasi suara kita sehingga memberikan efek menenangkan pada orang tersebut. Minta orang tersebut untuk menarik napas dalam-dalam. Anda dapat menggunakan beberapa teknik meditasi untuk membantu subjek rileks. Subjek harus memiliki kepercayaan penuh pada Anda. Penyerahan hipnosis tidak akan terjadi jika rasa takut bersembunyi di dalam pikiran subjek. Anda harus memberikan perintah atau sugesti hipnotis dan membuat orang tersebut mengalami trans. Biarkan ini bertahap. Dengan suara yang tenang, ulangi perintah tertentu. Anda dapat menempatkan kesadaran subjek pada bagian tubuh yang berbeda. Gunakan pernyataan seperti &#8216;sadari lengan Anda, rilekskan&#8217; dan gunakan perintah ini untuk area tubuh yang berbeda. Gunakan kata-kata yang membesarkan hati untuk membuat orang tersebut rileks. Bala bantuan yang positif akan membantu. Ketika subjek tampak seperti kesurupan, ulangi perintah yang mendorong subjek untuk jatuh ke dalam tidur yang lebih dalam. Pernyataan seperti &#8216;Anda tertidur lelap&#8217; atau &#8216;Anda merasa damai&#8217; dapat digunakan pada tahap ini. Anda dapat mencoba untuk menyembuhkan subjek atau mencoba menyelesaikan konflik batin subjek. Fobia, stres, dan kecanduan dapat disembuhkan dengan menggunakan hipnoterapi. Untuk mengakhiri sesi ini, Anda perlu memberi tahu subjek bahwa Anda akan menghitung sampai lima dan pada hitungan kelima, subjek akan keluar dari tidur nyenyaknya. Dengan setiap hitungan, Anda harus menyebutkan kata &#8216;bangun&#8217;. Subjek akan keluar dari kondisi trance.<\/p>\n\n<p class=\"wp-block-paragraph\">Sekarang setelah Anda memahami konsep hipnosis, pastikan Anda menggunakannya untuk membantu orang lain. Memikirkan hipnosis sebagai sarana untuk mengekstrak informasi yang bertentangan dengan keinginan mereka adalah tidak etis. Jika Anda dapat menguasai seni ini, akan lebih baik jika Anda menerapkan teknik ini untuk membantu orang lain menyelesaikan konflik batin mereka.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Akan ada banyak orang yang menganggap konsep hipnotis sangat menarik. Banyak yang mengasosiasikan hipnotis dengan semacam sihir, tapi biar saya beritahu, ini lebih seperti permainan pikiran. Jika Anda tahu cara menghipnotis secara instan, Anda dapat menggunakan perintah untuk masuk jauh ke dalam jiwa individu tersebut.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_surecart_dashboard_logo_width":"180px","_surecart_dashboard_show_logo":true,"_surecart_dashboard_navigation_orders":true,"_surecart_dashboard_navigation_invoices":true,"_surecart_dashboard_navigation_subscriptions":true,"_surecart_dashboard_navigation_downloads":true,"_surecart_dashboard_navigation_billing":true,"_surecart_dashboard_navigation_account":true,"_uag_custom_page_level_css":"","_swt_meta_header_display":false,"_swt_meta_footer_display":false,"_swt_meta_site_title_display":false,"_swt_meta_sticky_header":false,"_swt_meta_transparent_header":false,"footnotes":""},"categories":[2131],"tags":[],"class_list":["post-13345","post","type-post","status-publish","format-standard","hentry","category-hipnosis"],"spectra_custom_meta":{"_encloseme":["1"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_yoast_wpseo_focuskeywords":[""],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"_last_translation_edit_mode":["translation-editor"],"rank_math_og_content_image":["a:2:{s:5:\"check\";s:32:\"bdd38742105d4c3f103e302831a315fa\";s:6:\"images\";a:1:{i:0;s:114:\"https:\/\/wiweka.com\/wp-content\/uploads\/2019\/06\/How-t&#x43E;-Hypnotize-S&#x43E;m&#x435;&#x43E;n&#x435;-Instantly.jpg\";}}"],"_uag_css_file_name":["uag-css-13345.css"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"rank_math_internal_links_processed":["1"],"_uag_page_assets":["a:9:{s:3:\"css\";s:23542:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.wp-block-uagb-container.uagb-block-4147cb09 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4147cb09 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4147cb09 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4147cb09 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4147cb09 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4147cb09{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4147cb09 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4147cb09{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 0%;background-size: contain;background-attachment: scroll;background-image: url(https:\/\/wiweka.com\/wp-content\/uploads\/2024\/01\/padma.png);background-clip: padding-box;row-gap: 0px;column-gap: 20px;}.uagb-block-5c159209.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5c159209.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5c159209.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5c159209.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5c159209.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-advanced-heading.uagb-block-32bb3de3.wp-block-uagb-advanced-heading .uagb-heading-text{color: #856b5c;}.wp-block-uagb-advanced-heading.uagb-block-32bb3de3.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-32bb3de3.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-32bb3de3.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-32bb3de3.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-32bb3de3 .uagb-heading-text{text-transform: uppercase;font-size: 12px;}.wp-block-uagb-advanced-heading.uagb-block-4d882354.wp-block-uagb-advanced-heading .uagb-heading-text{color: #856b5c;}.wp-block-uagb-advanced-heading.uagb-block-4d882354.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-4d882354.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4d882354.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4d882354.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4d882354 .uagb-heading-text{text-transform: uppercase;font-size: 12px;}.wp-block-uagb-advanced-heading.uagb-block-e185c18b.wp-block-uagb-advanced-heading .uagb-heading-text{color: #856b5c;}.wp-block-uagb-advanced-heading.uagb-block-e185c18b.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e185c18b.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e185c18b.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e185c18b.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e185c18b .uagb-heading-text{text-transform: uppercase;font-size: 12px;}.wp-block-uagb-advanced-heading.uagb-block-ce923ebc.wp-block-uagb-advanced-heading .uagb-heading-text{color: #856b5c;}.wp-block-uagb-advanced-heading.uagb-block-ce923ebc.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ce923ebc.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ce923ebc.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ce923ebc.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ce923ebc .uagb-heading-text{text-transform: uppercase;font-size: 12px;}.wp-block-uagb-advanced-heading.uagb-block-ba59b695.wp-block-uagb-advanced-heading .uagb-heading-text{color: #856b5c;}.wp-block-uagb-advanced-heading.uagb-block-ba59b695.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ba59b695.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ba59b695.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ba59b695.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ba59b695 .uagb-heading-text{text-transform: uppercase;font-size: 12px;}.wp-block-uagb-advanced-heading.uagb-block-af466d70.wp-block-uagb-advanced-heading .uagb-heading-text{color: #856b5c;}.wp-block-uagb-advanced-heading.uagb-block-af466d70.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-af466d70.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-af466d70.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-af466d70.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-af466d70 .uagb-heading-text{text-transform: uppercase;font-size: 12px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4147cb09{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4147cb09 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4147cb09{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/wiweka.com\/wp-content\/uploads\/2024\/01\/padma.png);background-clip: padding-box;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4147cb09{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4147cb09 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4147cb09{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/wiweka.com\/wp-content\/uploads\/2024\/01\/padma.png);background-clip: padding-box;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-5c159209.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:71:{i:0;s:14:\"uagb\/container\";i:1;s:10:\"core\/group\";i:4;s:14:\"core\/shortcode\";i:6;s:12:\"core\/buttons\";i:7;s:11:\"core\/button\";i:10;s:14:\"core\/site-logo\";i:12;s:12:\"core\/heading\";i:14;s:10:\"uagb\/image\";i:15;s:15:\"core\/navigation\";i:18;s:24:\"core\/post-featured-image\";i:20;s:12:\"core\/columns\";i:21;s:11:\"core\/column\";i:25;s:10:\"core\/image\";i:26;s:21:\"uagb\/advanced-heading\";i:29;s:15:\"core\/post-title\";i:31;s:16:\"core\/post-author\";i:32;s:14:\"core\/paragraph\";i:33;s:14:\"core\/post-date\";i:34;s:15:\"core\/post-terms\";i:39;s:17:\"core\/post-content\";i:41;s:13:\"core\/comments\";i:42;s:19:\"core\/comments-title\";i:43;s:21:\"core\/comment-template\";i:46;s:11:\"core\/avatar\";i:48;s:24:\"core\/comment-author-name\";i:50;s:17:\"core\/comment-date\";i:51;s:22:\"core\/comment-edit-link\";i:52;s:20:\"core\/comment-content\";i:53;s:23:\"core\/comment-reply-link\";i:54;s:24:\"core\/comments-pagination\";i:55;s:33:\"core\/comments-pagination-previous\";i:56;s:32:\"core\/comments-pagination-numbers\";i:57;s:29:\"core\/comments-pagination-next\";i:58;s:23:\"core\/post-comments-form\";i:59;s:15:\"core\/categories\";i:60;s:14:\"core\/separator\";i:61;s:17:\"core\/latest-posts\";i:62;s:15:\"core\/site-title\";i:63;s:9:\"core\/more\";i:64;s:23:\"surecart\/slide-out-cart\";i:66;s:26:\"surecart\/cart-close-button\";i:67;s:19:\"surecart\/cart-count\";i:69;s:34:\"surecart\/slide-out-cart-line-items\";i:72;s:29:\"surecart\/cart-line-item-image\";i:76;s:29:\"surecart\/cart-line-item-title\";i:78;s:34:\"surecart\/cart-line-item-price-name\";i:79;s:31:\"surecart\/cart-line-item-variant\";i:80;s:28:\"surecart\/cart-line-item-note\";i:81;s:30:\"surecart\/cart-line-item-status\";i:84;s:38:\"surecart\/cart-line-item-scratch-amount\";i:85;s:30:\"surecart\/cart-line-item-amount\";i:86;s:32:\"surecart\/cart-line-item-interval\";i:88;s:29:\"surecart\/cart-line-item-trial\";i:89;s:28:\"surecart\/cart-line-item-fees\";i:92;s:32:\"surecart\/cart-line-item-quantity\";i:94;s:30:\"surecart\/cart-line-item-remove\";i:96;s:25:\"surecart\/cart-order-bumps\";i:97;s:35:\"surecart\/cart-order-bump-pagination\";i:98;s:44:\"surecart\/cart-order-bump-pagination-previous\";i:99;s:40:\"surecart\/cart-order-bump-pagination-next\";i:100;s:33:\"surecart\/cart-order-bump-template\";i:102;s:30:\"surecart\/cart-order-bump-image\";i:104;s:30:\"surecart\/cart-order-bump-title\";i:105;s:36:\"surecart\/cart-order-bump-description\";i:107;s:39:\"surecart\/cart-order-bump-scratch-amount\";i:108;s:31:\"surecart\/cart-order-bump-amount\";i:109;s:35:\"surecart\/cart-order-bump-add-button\";i:111;s:38:\"surecart\/slide-out-cart-items-subtotal\";i:113;s:37:\"surecart\/cart-subtotal-scratch-amount\";i:114;s:29:\"surecart\/cart-subtotal-amount\";i:115;s:36:\"surecart\/slide-out-cart-items-submit\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1784098868\";s:6:\"gfonts\";a:1:{s:7:\"Default\";a:2:{s:10:\"fontfamily\";s:7:\"Default\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:77:\"https:\/\/fonts.googleapis.com\/css?family=Default&subset=latin&display=fallback\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Wiweka","author_link":"https:\/\/wiweka.com\/id\/author\/wiweka\/"},"uagb_comment_info":0,"uagb_excerpt":"Akan ada banyak orang yang menganggap konsep hipnotis sangat menarik. Banyak yang mengasosiasikan hipnotis dengan semacam sihir, tapi biar saya beritahu, ini lebih seperti permainan pikiran. Jika Anda tahu cara menghipnotis secara instan, Anda dapat menggunakan perintah untuk masuk jauh ke dalam jiwa individu tersebut.","_links":{"self":[{"href":"https:\/\/wiweka.com\/id\/wp-json\/wp\/v2\/posts\/13345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wiweka.com\/id\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wiweka.com\/id\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wiweka.com\/id\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wiweka.com\/id\/wp-json\/wp\/v2\/comments?post=13345"}],"version-history":[{"count":0,"href":"https:\/\/wiweka.com\/id\/wp-json\/wp\/v2\/posts\/13345\/revisions"}],"wp:attachment":[{"href":"https:\/\/wiweka.com\/id\/wp-json\/wp\/v2\/media?parent=13345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wiweka.com\/id\/wp-json\/wp\/v2\/categories?post=13345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wiweka.com\/id\/wp-json\/wp\/v2\/tags?post=13345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}